{"id":17,"count":5,"description":"","link":"https:\/\/dohire.com\/blog\/category\/skip-hire\/","name":"Skip Hire","slug":"skip-hire","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Skip Hire Archives - Welcome to the DoHire Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dohire.com\/blog\/category\/skip-hire\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skip Hire Archives - Welcome to the DoHire Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dohire.com\/blog\/category\/skip-hire\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome to the DoHire Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dohire.com\/blog\/#website\",\"url\":\"https:\/\/dohire.com\/blog\/\",\"name\":\"Welcome to the DoHire Blog\",\"description\":\"Tips and Turtorials for DIY Enthusiasts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dohire.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/dohire.com\/blog\/category\/skip-hire\/#webpage\",\"url\":\"https:\/\/dohire.com\/blog\/category\/skip-hire\/\",\"name\":\"Skip Hire Archives - Welcome to the DoHire Blog\",\"isPartOf\":{\"@id\":\"https:\/\/dohire.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/dohire.com\/blog\/category\/skip-hire\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dohire.com\/blog\/category\/skip-hire\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dohire.com\/blog\/category\/skip-hire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dohire.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Skip Hire\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Skip Hire Archives - Welcome to the DoHire Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dohire.com\/blog\/category\/skip-hire\/","og_locale":"en_GB","og_type":"article","og_title":"Skip Hire Archives - Welcome to the DoHire Blog","og_url":"https:\/\/dohire.com\/blog\/category\/skip-hire\/","og_site_name":"Welcome to the DoHire Blog","twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dohire.com\/blog\/#website","url":"https:\/\/dohire.com\/blog\/","name":"Welcome to the DoHire Blog","description":"Tips and Turtorials for DIY Enthusiasts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dohire.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"CollectionPage","@id":"https:\/\/dohire.com\/blog\/category\/skip-hire\/#webpage","url":"https:\/\/dohire.com\/blog\/category\/skip-hire\/","name":"Skip Hire Archives - Welcome to the DoHire Blog","isPartOf":{"@id":"https:\/\/dohire.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/dohire.com\/blog\/category\/skip-hire\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dohire.com\/blog\/category\/skip-hire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dohire.com\/blog\/category\/skip-hire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dohire.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Skip Hire"}]}]}},"_links":{"self":[{"href":"https:\/\/dohire.com\/blog\/wp-json\/wp\/v2\/categories\/17"}],"collection":[{"href":"https:\/\/dohire.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dohire.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dohire.com\/blog\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}